{"id":4805,"date":"2023-03-28T10:46:35","date_gmt":"2023-03-28T16:46:35","guid":{"rendered":"https:\/\/idsinc.com\/?p=4805"},"modified":"2026-03-05T16:58:55","modified_gmt":"2026-03-05T22:58:55","slug":"time-zones","status":"publish","type":"post","link":"https:\/\/idsinc.com\/es\/time-zones\/","title":{"rendered":"Zonas horarias"},"content":{"rendered":"<!-- wp:themify-builder\/canvas \/-->\n\n\n<h3 class=\"wp-block-heading\"><strong>El resumen<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Existe una buena posibilidad de que algunas, muchas o todas las marcas de tiempo en su descubrimiento electr\u00f3nico sean incorrectas. Tambi\u00e9n hay una buena probabilidad de que no importe. Hasta que lo haga. Este art\u00edculo resaltar\u00e1 el problema, la soluci\u00f3n y los puntos de decisi\u00f3n asociados con la confirmaci\u00f3n de zona horaria en E-discovery.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>El tiempo lo es todo... particularmente cuando se trata de zonas horarias. Considere la siguiente historia de guerra:&nbsp;<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u00bfEl demandado envi\u00f3 el correo electr\u00f3nico clave en el esquema de fraude, o el demandado tuvo un accidente casi fatal 15 minutos antes de que se enviara el correo electr\u00f3nico?<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Resulta que el correo electr\u00f3nico se envi\u00f3 45 minutos antes del accidente pero desde una zona horaria diferente. Esto cambi\u00f3 el resultado del juicio.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estar en el lugar correcto en el momento correcto a veces puede marcar la diferencia en tu vida. Como dice el dicho,<em> tiempo lo es todo<\/em>. Esto es particularmente cierto en el contexto de los litigios. El tiempo es primordial cuando se trata de interpretar muchos de los puntos de datos y conversaciones en la evidencia.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Houston, tenemos un problema (de tiempo)<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">No es raro que los programas de software registren la zona horaria junto con las marcas de tiempo. Esto permite que un procesador de datos diligente sincronice todas las marcas de tiempo en la misma zona horaria. Por lo general, pero pueden ocurrir errores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, es posible que no se registre la zona horaria. Esto provoca la necesidad de investigar cu\u00e1l debe ser la zona horaria correcta. En todos los casos, existe cierto grado de ambig\u00fcedad o error en la interpretaci\u00f3n de las zonas horarias. Sin embargo, en nuestra experiencia, rara vez importa... hasta que lo hace.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Muchos casos tienen correos electr\u00f3nicos y otras comunicaciones que se recopilan, presentan y admiten como evidencia sin problemas. A veces, incluso si las zonas horarias de los mensajes individuales son incorrectas, simplemente no importa.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Caso en punto: <em>\u00bfSe envi\u00f3 un contrato? \u00bfFue aceptado? <\/em>La hora del d\u00eda en que se envi\u00f3 el contrato puede ser irrelevante si est\u00e1 claro que un contrato se envi\u00f3 en enero pero se acept\u00f3 en febrero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por otro lado, existen circunstancias espec\u00edficas en las que la sincronizaci\u00f3n precisa y, en consecuencia, la zona horaria, son de importancia cr\u00edtica.\u00a0<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>La fuente del problema<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Todo el concepto de zonas horarias y horario de verano es bastante ca\u00f3tico. Aunque solo hay veinticuatro horas en un d\u00eda, hay cuarenta y dos zonas horarias en el mundo. De los cuatro pa\u00edses m\u00e1s grandes del mundo, Rusia tiene once zonas horarias (actualmente). Canad\u00e1 tiene seis. China tiene uno. Estados Unidos tiene seis. La mayor parte del mundo no utiliza el horario de verano, incluidos Haw\u00e1i, Arizona, Puerto Rico y las Islas V\u00edrgenes de EE. UU. Hubo un tiempo en que Iowa ten\u00eda veintitr\u00e9s zonas horarias diferentes para el horario de verano. El horario de verano no solo afecta a los estadounidenses. Crea confusi\u00f3n entre los ciudadanos de muchos pa\u00edses, particularmente cuando se programan reuniones o conferencias internacionales en l\u00ednea. Sin mencionar que no siempre cae el mismo d\u00eda para cada pa\u00eds ni la fecha es consistente cada a\u00f1o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una raz\u00f3n com\u00fan por la que las zonas horarias son incorrectas es que muchos sistemas heredados no indican la zona horaria de las marcas de tiempo que registran. Entonces no queda claro si una marca de tiempo se basa en la ubicaci\u00f3n del actor, la sede de la empresa o el servidor de aplicaciones de datos. Otra raz\u00f3n por la que las zonas horarias pueden ser inexactas es que los diferentes sistemas registran las fechas de diferentes maneras. Los sistemas basados en Microsoft utilizan una metodolog\u00eda independiente de los sistemas basados en Unix (tenga cuidado al comparar los mensajes de Bloomberg con MS Exchange).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La tercera raz\u00f3n por la que las zonas horarias suelen ser incorrectas es que varios procesadores de datos (proveedores de exhibici\u00f3n de documentos electr\u00f3nicos) pueden haber estado involucrados en un solo caso. Cada uno de estos proveedores puede haber utilizado un m\u00e9todo de conversi\u00f3n diferente.<br><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>La importancia del problema<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Como se mencion\u00f3 anteriormente, en muchos casos, la hora exacta de un evento no es significativa. Pero a veces puede ser. El <em><u>absoluto<\/u><\/em> El tiempo de un elemento de prueba puede ser el factor decisivo en un caso. Por ejemplo, \u00bfla informaci\u00f3n se recibi\u00f3 el 31 de diciembre o el 1 de enero? Si se envi\u00f3 un correo electr\u00f3nico desde Nueva York el 31 de diciembre de 2022 a las 9 p. m. EST (hora est\u00e1ndar del este) pero se recibi\u00f3 en Londres a las 2 a.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El <em><u>relativo<\/u><\/em> La secuencia de pruebas tambi\u00e9n puede ser un factor decisivo en un caso. \u00bfOcurri\u00f3 el evento A antes o despu\u00e9s del evento B? Cuando estos se registran en diferentes sistemas, es crucial asegurarse de que las zonas horarias est\u00e9n correctamente ajustadas. Si bien las marcas de tiempo y fecha pueden proporcionar una medida objetiva de cu\u00e1ndo sucedi\u00f3 algo, no siempre podemos tomar una marca de tiempo al pie de la letra. En circunstancias clave, debe haber una verificaci\u00f3n de las marcas de tiempo (y la evidencia) para garantizar que no se alter\u00f3 nada, intencionalmente o no. Cuando surgen esas situaciones, contar con un equipo de expertos como iDS para confirmar la autenticidad de los datos es esencial para determinar la legitimidad de los sellos de fecha y hora en cuesti\u00f3n.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Un ejemplo<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Los diferentes pa\u00edses, estados y ciudades tienen diferentes zonas horarias, lo que genera incertidumbre sobre a qu\u00e9 hora se envi\u00f3 o recibi\u00f3 un documento. Esto contribuye a la confusi\u00f3n y los errores, lo que hace que el testimonio de los testigos no sea confiable. Como resultado, no podemos confiar \u00fanicamente en el testimonio de los testigos. Los datos son m\u00e1s consistentes y siempre entregar\u00e1n un registro imparcial y preciso. La experiencia en miner\u00eda de datos de iDS puede brindarle una ventaja en los tribunales. Hemos probado con \u00e9xito cuando los datos fueron manipulados y\/o destruidos. Tambi\u00e9n identificamos con \u00e9xito cu\u00e1ndo y d\u00f3nde se enviaron hilos de correo electr\u00f3nico e intercambios de texto despu\u00e9s de declaraciones o documentos falsificados que intentaron afirmar lo contrario.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para ilustrar un ejemplo, una vez se nos present\u00f3 un caso al que podemos referirnos como &quot;La disputa por correo electr\u00f3nico de Nashville&quot; en el que pudimos probar mediante an\u00e1lisis forense digital que el acusado hab\u00eda creado una cuenta de correo electr\u00f3nico falsa y un hilo falso de pagos y acuerdos de descuento. . Determinamos que el correo electr\u00f3nico clave en cuesti\u00f3n se envi\u00f3 en una zona horaria diferente a la que reclamaba el demandado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>El abogado del demandante declar\u00f3: \u201cSu se\u00f1or\u00eda, damas y caballeros del jurado, este es un caso simple de fraude y enga\u00f1o, realizado con correos electr\u00f3nicos falsos. El acusado se ha involucrado en un plan intencional y bien ejecutado para crear una conversaci\u00f3n falsa con una cuenta de correo electr\u00f3nico falsa. Esto se hace con el fin de crear un rastro de falsas promesas y compromisos para evitar pagarle a mi cliente el dinero que se le debe\u201d.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>El abogado defensor respondi\u00f3: \u201cEso no es posible. De hecho, escuchar\u00e1 del State Trooper que su evidencia clave, el \u00faltimo y m\u00e1s pertinente correo electr\u00f3nico que acusaron de enviar a mi cliente, en realidad se envi\u00f3 15 minutos despu\u00e9s. <u>despu\u00e9s<\/u> mi cliente tuvo un horrible accidente que lo puso en coma\u201d.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>El abogado del demandante estaba preparado para que esta defensa tomara esta posici\u00f3n y respondi\u00f3: \u201cEn realidad, se envi\u00f3 el correo electr\u00f3nico. Debido a que Tennessee tiene dos husos horarios, envi\u00f3 el correo electr\u00f3nico antes del accidente, desde el este de Tennessee, y luego entr\u00f3 en el accidente en el oeste de Tennessee, por lo que el reloj mostr\u00f3 una hora antes\u201d.&nbsp;<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El demandante gan\u00f3 la demanda. El acusado no solo perdi\u00f3 el caso y pag\u00f3 el dinero, sino que tambi\u00e9n fue sentenciado a prisi\u00f3n.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>\u00bfCu\u00e1ndo importa?<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfC\u00f3mo puede determinar el abogado cu\u00e1ndo gastar el dinero para verificar las zonas horarias cuando a menudo son incorrectas, ya sea en su totalidad o en parte?<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Cuando hay una actividad sustancial cerca del l\u00edmite de descubrimiento<\/li>\n\n\n\n<li>Cuando hay un momento crucial<\/li>\n\n\n\n<li>Cuando hay un evento cr\u00edtico<\/li>\n\n\n\n<li>Al desarrollar tendencias anuales que abarcan el horario de verano<\/li>\n\n\n\n<li>Al combinar datos de m\u00faltiples fuentes<\/li>\n\n\n\n<li>Al combinar datos de varias ubicaciones<\/li>\n\n\n\n<li>Cuando la evidencia simplemente no cuadra<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Las zonas horarias se malinterpretan f\u00e1cilmente. Puede que no importe en muchos casos, pero si lo hace, debe identificar si el l\u00edmite est\u00e1 al principio o al final del descubrimiento. Si hay pruebas singulares que son relevantes, entonces la zona horaria es una cosa para validar. Esto se debe a que la hora l\u00edmite puede diferir entre zonas horarias. Es posible que tenga pruebas de una zona horaria que estar\u00edan excluidas en otra y viceversa. Por lo tanto, es importante tener en cuenta con precisi\u00f3n la diferencia horaria para garantizar que no se pase por alto ninguna evidencia significativa. Por ejemplo, si tiene un l\u00edmite para un proceso de descubrimiento que es medianoche en una zona horaria y son las 11:59 p. m. en otra zona horaria, es posible que se pierda un documento valioso si no tiene en cuenta la diferencia horaria.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los litigantes deben asumir que todas las marcas de tiempo pueden ser incorrectas en su zona horaria. Si no importa, est\u00e1 bien, pero si importa, t\u00f3malo en consideraci\u00f3n. Esto es particularmente cierto cuando se trata de casos internacionales, ya que las zonas horarias pueden variar mucho. Es necesario tener en cuenta la posibilidad de que las marcas de tiempo se desv\u00eden unas horas o incluso un d\u00eda. Esto es para que los litigantes puedan tomar las decisiones m\u00e1s informadas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La movilidad tambi\u00e9n es un problema. A medida que aumenta la cantidad de personas que trabajan desde casa, tambi\u00e9n es imperativo conocer la complejidad de las zonas horarias de la oficina, las zonas horarias del servidor, las zonas horarias de la oficina en el hogar de los empleados, las zonas horarias de ubicaci\u00f3n de los empleados, las zonas horarias de los destinatarios y las zonas horarias universales. \u00bfAlguna vez not\u00f3 una cadena de correo electr\u00f3nico donde parece que se envi\u00f3 la respuesta? <em><u>antes<\/u><\/em> el correo original?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No olvidemos los desaf\u00edos que surgen con la recolecci\u00f3n y el procesamiento. En muchos casos, la recopilaci\u00f3n y el procesamiento de datos electr\u00f3nicos es complejo debido al gran volumen y la variedad de fuentes de datos que pueden necesitar revisi\u00f3n. Esto puede complicarse a\u00fan m\u00e1s por las diferentes ubicaciones y zonas horarias de las partes involucradas, as\u00ed como por los diferentes requisitos jurisdiccionales del tribunal. \u00bfDeber\u00edan formatearse los correos electr\u00f3nicos de acuerdo con el destinatario, el remitente, la ubicaci\u00f3n de la sede corporativa (y el servidor de correo electr\u00f3nico), la ubicaci\u00f3n de recopilaci\u00f3n, la ubicaci\u00f3n del proveedor de ESI, el GMT o la jurisdicci\u00f3n del tribunal? \u00a1Hemos visto todo esto, incluso en el mismo caso!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al realizar eDiscovery de calidad, puede identificar las debilidades en las afirmaciones y argumentos de la otra parte. Adem\u00e1s, puede determinar evidencia potencial y encontrar hechos que ser\u00e1n beneficiosos para su caso. Conocer los argumentos opuestos de la otra parte y los materiales de respaldo le permitir\u00e1n anticipar los posibles resultados y contraargumentos y posicionarse mejor para las decisiones judiciales. Obtenga una ventaja estrat\u00e9gica investigando cualquier marca de tiempo o discrepancia de zona horaria. Es esencial asegurarse de que los datos de la zona horaria se verifiquen con precisi\u00f3n al integrar evidencia de m\u00faltiples fuentes externas. Esto puede tener implicaciones importantes para el resultado del caso de su cliente. Se vuelve a\u00fan m\u00e1s relevante a medida que incluimos m\u00e1s y m\u00e1s datos de dispositivos inteligentes e Internet de las cosas.<br><br>Esto no quiere decir que los testigos no tengan credibilidad, pero a veces la memoria puede no ser confiable. La gente olvida. A veces se olvidan a prop\u00f3sito. En particular, la gente tiende a subestimar o sobrestimar la duraci\u00f3n del tiempo. Recuerda en<em> Mi primo Vinny,<\/em> el contrainterrogatorio sobre cu\u00e1nto tiempo llev\u00f3 cocinar s\u00e9mola? Para corregir el recuerdo falso del tiempo que el autom\u00f3vil del sospechoso estuvo en la estaci\u00f3n de servicio, se compar\u00f3 el tiempo con el tiempo que tom\u00f3 cocinar un taz\u00f3n de s\u00e9mola.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las marcas de tiempo y las zonas horarias son elementos clave cuando se trata de descubrir pruebas y probar su caso. Como sabemos, el tiempo lo es todo. No hay sustituto para ello, as\u00ed que aseg\u00farese de que puede realizar un seguimiento de hasta el \u00faltimo detalle esencial.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-alpha-channel-opacity has-background is-style-wide\" style=\"background-color:#e1e1e1;color:#e1e1e1\"\/>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>iDS proporciona soluciones de datos de consulta a corporaciones y bufetes de abogados de todo el mundo, lo que les otorga una ventaja decisiva, tanto dentro como fuera de la sala del tribunal. Nuestros expertos en la materia y estrategas de datos se especializan en encontrar soluciones a problemas de datos complejos, lo que garantiza que los datos se puedan aprovechar como un activo y no como un pasivo.<\/em><\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>The Summary There is a good chance that some, many, or all of the timestamps in your E-discovery are incorrect. There is also a good chance that it doesn\u2019t matter. Until it does. This article will highlight the problem, the solution, and the decision points associated with time zone confirmation in E-discovery. Timing is Everything&#8230; [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":4808,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,30],"tags":[],"class_list":["post-4805","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-digital-evidence","has-post-title","has-post-date","has-post-category","has-post-tag","has-post-comment","has-post-author",""],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Time Zones - iDiscovery Solutions<\/title>\n<meta name=\"description\" content=\"There is a chance that timestamps in your E-discovery are wrong. Time zone confirmation in E-discovery could determine the fate of your case.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/idsinc.com\/es\/time-zones\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Time Zones\" \/>\n<meta property=\"og:description\" content=\"There is a chance that timestamps in your E-discovery are wrong. Time zone confirmation in E-discovery could determine the fate of your case.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/idsinc.com\/es\/time-zones\/\" \/>\n<meta property=\"og:site_name\" content=\"iDiscovery Solutions\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/iDiscovery-Solutions-110210573904472\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-28T16:46:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-05T22:58:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/idsinc.com\/wp-content\/uploads\/2023\/03\/Time-Zones-iDiscovery-Solutions-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dan Regard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dan Regard\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/idsinc.com\\\/time-zones\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/idsinc.com\\\/time-zones\\\/\"},\"author\":{\"name\":\"Dan Regard\",\"@id\":\"https:\\\/\\\/idsinc.com\\\/en_gb\\\/#\\\/schema\\\/person\\\/803ad31781146823f476911393d83156\"},\"headline\":\"Time Zones\",\"datePublished\":\"2023-03-28T16:46:35+00:00\",\"dateModified\":\"2026-03-05T22:58:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/idsinc.com\\\/time-zones\\\/\"},\"wordCount\":1950,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/idsinc.com\\\/en_gb\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/idsinc.com\\\/time-zones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/idsinc.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Time-Zones-iDiscovery-Solutions-scaled.jpg\",\"articleSection\":[\"Blog\",\"Digital Evidence + Data Authenticity\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/idsinc.com\\\/time-zones\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/idsinc.com\\\/time-zones\\\/\",\"url\":\"https:\\\/\\\/idsinc.com\\\/time-zones\\\/\",\"name\":\"Time Zones - iDiscovery Solutions\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/idsinc.com\\\/en_gb\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/idsinc.com\\\/time-zones\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/idsinc.com\\\/time-zones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/idsinc.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Time-Zones-iDiscovery-Solutions-scaled.jpg\",\"datePublished\":\"2023-03-28T16:46:35+00:00\",\"dateModified\":\"2026-03-05T22:58:55+00:00\",\"description\":\"There is a chance that timestamps in your E-discovery are wrong. Time zone confirmation in E-discovery could determine the fate of your case.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/idsinc.com\\\/time-zones\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/idsinc.com\\\/time-zones\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/idsinc.com\\\/time-zones\\\/#primaryimage\",\"url\":\"https:\\\/\\\/idsinc.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Time-Zones-iDiscovery-Solutions-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/idsinc.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Time-Zones-iDiscovery-Solutions-scaled.jpg\",\"width\":1200,\"height\":600,\"caption\":\"There is a chance that the timestamps in your E-discovery are wrong. Time zone confirmation in E-discovery could determine the fate of your case.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/idsinc.com\\\/time-zones\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/idsinc.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/idsinc.com\\\/de\\\/category\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Time Zones\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/idsinc.com\\\/en_gb\\\/#website\",\"url\":\"https:\\\/\\\/idsinc.com\\\/en_gb\\\/\",\"name\":\"iDiscovery Solutions\",\"description\":\"Use data to your advantage in the courtroom\",\"publisher\":{\"@id\":\"https:\\\/\\\/idsinc.com\\\/en_gb\\\/#organization\"},\"alternateName\":\"iDS\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/idsinc.com\\\/en_gb\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/idsinc.com\\\/en_gb\\\/#organization\",\"name\":\"iDiscovery Solutions\",\"alternateName\":\"iDS\",\"url\":\"https:\\\/\\\/idsinc.com\\\/en_gb\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/idsinc.com\\\/en_gb\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/idsinc.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/iDS-Logo-3c-e1611176096212.png\",\"contentUrl\":\"https:\\\/\\\/idsinc.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/iDS-Logo-3c-e1611176096212.png\",\"width\":100,\"height\":73,\"caption\":\"iDiscovery Solutions\"},\"image\":{\"@id\":\"https:\\\/\\\/idsinc.com\\\/en_gb\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/iDiscovery-Solutions-110210573904472\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/idsinc\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCarv7o1MeYfCp0eZ1IrufIw\"],\"description\":\"iDS provides consultative data solutions to corporations and law firms around the world, giving them a decisive advantage \u2013 both in and out of the courtroom. iDS\u2019s subject matter experts and data strategists specialize in finding solutions to complex data problems, ensuring data can be leveraged as an asset, not a liability.\",\"email\":\"info@idsinc.com\",\"telephone\":\"+1.800.813.4832\",\"legalName\":\"iDiscovery Solutions\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/idsinc.com\\\/en_gb\\\/#\\\/schema\\\/person\\\/803ad31781146823f476911393d83156\",\"name\":\"Dan Regard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/71f395a2e924fed8327f7eae9a8e3f3c021847644b1cea8c14a20b0396aa22f1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/71f395a2e924fed8327f7eae9a8e3f3c021847644b1cea8c14a20b0396aa22f1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/71f395a2e924fed8327f7eae9a8e3f3c021847644b1cea8c14a20b0396aa22f1?s=96&d=mm&r=g\",\"caption\":\"Dan Regard\"},\"url\":\"https:\\\/\\\/idsinc.com\\\/es\\\/author\\\/dan\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Zonas horarias - Soluciones iDiscovery","description":"Existe la posibilidad de que las marcas de tiempo en su descubrimiento electr\u00f3nico sean incorrectas. La confirmaci\u00f3n de la zona horaria en E-discovery podr\u00eda determinar el destino de su caso.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/idsinc.com\/es\/time-zones\/","og_locale":"es_ES","og_type":"article","og_title":"Time Zones","og_description":"There is a chance that timestamps in your E-discovery are wrong. Time zone confirmation in E-discovery could determine the fate of your case.","og_url":"https:\/\/idsinc.com\/es\/time-zones\/","og_site_name":"iDiscovery Solutions","article_publisher":"https:\/\/www.facebook.com\/iDiscovery-Solutions-110210573904472","article_published_time":"2023-03-28T16:46:35+00:00","article_modified_time":"2026-03-05T22:58:55+00:00","og_image":[{"width":1200,"height":600,"url":"https:\/\/idsinc.com\/wp-content\/uploads\/2023\/03\/Time-Zones-iDiscovery-Solutions-scaled.jpg","type":"image\/jpeg"}],"author":"Dan Regard","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Dan Regard","Tiempo de lectura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/idsinc.com\/time-zones\/#article","isPartOf":{"@id":"https:\/\/idsinc.com\/time-zones\/"},"author":{"name":"Dan Regard","@id":"https:\/\/idsinc.com\/en_gb\/#\/schema\/person\/803ad31781146823f476911393d83156"},"headline":"Time Zones","datePublished":"2023-03-28T16:46:35+00:00","dateModified":"2026-03-05T22:58:55+00:00","mainEntityOfPage":{"@id":"https:\/\/idsinc.com\/time-zones\/"},"wordCount":1950,"commentCount":0,"publisher":{"@id":"https:\/\/idsinc.com\/en_gb\/#organization"},"image":{"@id":"https:\/\/idsinc.com\/time-zones\/#primaryimage"},"thumbnailUrl":"https:\/\/idsinc.com\/wp-content\/uploads\/2023\/03\/Time-Zones-iDiscovery-Solutions-scaled.jpg","articleSection":["Blog","Digital Evidence + Data Authenticity"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/idsinc.com\/time-zones\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/idsinc.com\/time-zones\/","url":"https:\/\/idsinc.com\/time-zones\/","name":"Zonas horarias - Soluciones iDiscovery","isPartOf":{"@id":"https:\/\/idsinc.com\/en_gb\/#website"},"primaryImageOfPage":{"@id":"https:\/\/idsinc.com\/time-zones\/#primaryimage"},"image":{"@id":"https:\/\/idsinc.com\/time-zones\/#primaryimage"},"thumbnailUrl":"https:\/\/idsinc.com\/wp-content\/uploads\/2023\/03\/Time-Zones-iDiscovery-Solutions-scaled.jpg","datePublished":"2023-03-28T16:46:35+00:00","dateModified":"2026-03-05T22:58:55+00:00","description":"Existe la posibilidad de que las marcas de tiempo en su descubrimiento electr\u00f3nico sean incorrectas. La confirmaci\u00f3n de la zona horaria en E-discovery podr\u00eda determinar el destino de su caso.","breadcrumb":{"@id":"https:\/\/idsinc.com\/time-zones\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/idsinc.com\/time-zones\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/idsinc.com\/time-zones\/#primaryimage","url":"https:\/\/idsinc.com\/wp-content\/uploads\/2023\/03\/Time-Zones-iDiscovery-Solutions-scaled.jpg","contentUrl":"https:\/\/idsinc.com\/wp-content\/uploads\/2023\/03\/Time-Zones-iDiscovery-Solutions-scaled.jpg","width":1200,"height":600,"caption":"There is a chance that the timestamps in your E-discovery are wrong. Time zone confirmation in E-discovery could determine the fate of your case."},{"@type":"BreadcrumbList","@id":"https:\/\/idsinc.com\/time-zones\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/idsinc.com\/"},{"@type":"ListItem","position":2,"name":"Blog","item":"https:\/\/idsinc.com\/de\/category\/blog\/"},{"@type":"ListItem","position":3,"name":"Time Zones"}]},{"@type":"WebSite","@id":"https:\/\/idsinc.com\/en_gb\/#website","url":"https:\/\/idsinc.com\/en_gb\/","name":"Soluciones iDiscovery","description":"Utilice los datos a su favor en la sala del tribunal","publisher":{"@id":"https:\/\/idsinc.com\/en_gb\/#organization"},"alternateName":"iDS","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/idsinc.com\/en_gb\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/idsinc.com\/en_gb\/#organization","name":"Soluciones iDiscovery","alternateName":"iDS","url":"https:\/\/idsinc.com\/en_gb\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/idsinc.com\/en_gb\/#\/schema\/logo\/image\/","url":"https:\/\/idsinc.com\/wp-content\/uploads\/2021\/01\/iDS-Logo-3c-e1611176096212.png","contentUrl":"https:\/\/idsinc.com\/wp-content\/uploads\/2021\/01\/iDS-Logo-3c-e1611176096212.png","width":100,"height":73,"caption":"iDiscovery Solutions"},"image":{"@id":"https:\/\/idsinc.com\/en_gb\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/iDiscovery-Solutions-110210573904472","https:\/\/www.linkedin.com\/company\/idsinc","https:\/\/www.youtube.com\/channel\/UCarv7o1MeYfCp0eZ1IrufIw"],"description":"iDS ofrece soluciones de datos consultivas a corporaciones y bufetes de abogados de todo el mundo, lo que les otorga una ventaja decisiva, tanto dentro como fuera de los tribunales. Los expertos en la materia y los estrategas de datos de iDS se especializan en encontrar soluciones a problemas de datos complejos, garantizando que los datos puedan aprovecharse como un activo, no como un pasivo.","email":"info@idsinc.com","telephone":"+1.800.813.4832","legalName":"iDiscovery Solutions"},{"@type":"Person","@id":"https:\/\/idsinc.com\/en_gb\/#\/schema\/person\/803ad31781146823f476911393d83156","name":"dan respeto","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/71f395a2e924fed8327f7eae9a8e3f3c021847644b1cea8c14a20b0396aa22f1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/71f395a2e924fed8327f7eae9a8e3f3c021847644b1cea8c14a20b0396aa22f1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/71f395a2e924fed8327f7eae9a8e3f3c021847644b1cea8c14a20b0396aa22f1?s=96&d=mm&r=g","caption":"Dan Regard"},"url":"https:\/\/idsinc.com\/es\/author\/dan\/"}]}},"builder_content":"","_links":{"self":[{"href":"https:\/\/idsinc.com\/es\/wp-json\/wp\/v2\/posts\/4805","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/idsinc.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/idsinc.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/idsinc.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/idsinc.com\/es\/wp-json\/wp\/v2\/comments?post=4805"}],"version-history":[{"count":1,"href":"https:\/\/idsinc.com\/es\/wp-json\/wp\/v2\/posts\/4805\/revisions"}],"predecessor-version":[{"id":9431,"href":"https:\/\/idsinc.com\/es\/wp-json\/wp\/v2\/posts\/4805\/revisions\/9431"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/idsinc.com\/es\/wp-json\/wp\/v2\/media\/4808"}],"wp:attachment":[{"href":"https:\/\/idsinc.com\/es\/wp-json\/wp\/v2\/media?parent=4805"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/idsinc.com\/es\/wp-json\/wp\/v2\/categories?post=4805"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/idsinc.com\/es\/wp-json\/wp\/v2\/tags?post=4805"}],"curies":[{"name":"gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}