{"id":4675,"date":"2023-02-23T15:42:58","date_gmt":"2023-02-23T21:42:58","guid":{"rendered":"https:\/\/idsinc.com\/?p=4675"},"modified":"2026-03-09T14:52:13","modified_gmt":"2026-03-09T20:52:13","slug":"new-bipa-regulations-in-illinois","status":"publish","type":"post","link":"https:\/\/idsinc.com\/es\/new-bipa-regulations-in-illinois\/","title":{"rendered":"<strong>Nuevas regulaciones de BIPA en Illinois<\/strong>"},"content":{"rendered":"<!-- wp:themify-builder\/canvas \/-->\n\n\n<p class=\"wp-block-paragraph\">La Corte Suprema de Illinois emiti\u00f3 recientemente una decisi\u00f3n en <a href=\"https:\/\/ilcourtsaudio.blob.core.windows.net\/antilles-resources\/resources\/e304b011-82d9-4832-9cae-d8205749a2ec\/Cothron%20v.%20White%20Castle%20System,%20Inc.,%202023%20IL%20128004.pdf\" target=\"_blank\" rel=\"noreferrer noopener\"><strong><em>Cothron contra White Castle System, Inc.<\/em><\/strong><\/a><strong><em>.<\/em><\/strong>, lo que podr\u00eda tener implicaciones significativas para el panorama de litigios y el entorno empresarial del estado. El caso se refer\u00eda a una supuesta violaci\u00f3n de la Ley de privacidad de informaci\u00f3n biom\u00e9trica (BIPA) de Illinois por parte de White Castle, una cadena de restaurantes de comida r\u00e1pida, en relaci\u00f3n con el uso de la tecnolog\u00eda de escaneo de huellas dactilares para fines de control de tiempo de los empleados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">BIPA requiere que las empresas obtengan el consentimiento informado por escrito de las personas antes de recopilar, usar o almacenar su informaci\u00f3n biom\u00e9trica, como huellas dactilares o escaneos faciales. Adem\u00e1s, la ley impone requisitos espec\u00edficos de notificaci\u00f3n y retenci\u00f3n de datos, as\u00ed como un derecho privado de acci\u00f3n que permite a las personas demandar por da\u00f1os y perjuicios si se violan sus derechos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el caso de Cothron, el demandante aleg\u00f3 que White Castle viol\u00f3 la BIPA al no proporcionar la notificaci\u00f3n adecuada y no obtener el consentimiento antes de recopilar y almacenar sus datos de huellas dactilares. El tribunal de primera instancia desestim\u00f3 el caso, pero el tribunal de apelaciones lo revoc\u00f3 y lo remiti\u00f3 para m\u00e1s procedimientos. White Castle apel\u00f3 la decisi\u00f3n ante la Corte Suprema de Illinois, que finalmente confirm\u00f3 el fallo de la corte de apelaciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La decisi\u00f3n de la Corte Suprema en <em>Cothron contra White Castle System, Inc.<\/em> podr\u00eda tener implicaciones significativas para las empresas que hacen negocios en Illinois.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Primero<\/strong>, aclara que un demandante no necesita demostrar da\u00f1os o lesiones reales para presentar un reclamo BIPA. En cambio, una violaci\u00f3n de los requisitos de notificaci\u00f3n y consentimiento de la ley es suficiente para establecer la legitimaci\u00f3n. Esto podr\u00eda potencialmente abrir la puerta a m\u00e1s demandas BIPA, ya que los demandantes pueden estar m\u00e1s dispuestos a demandar incluso si no han sufrido ning\u00fan da\u00f1o real.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Segundo<\/strong>, la decisi\u00f3n enfatiza la importancia de cumplir con los requisitos de notificaci\u00f3n y consentimiento de BIPA. El Tribunal rechaz\u00f3 el argumento de White Castle de que el reclamo del demandante era discutible porque la empresa hab\u00eda proporcionado la notificaci\u00f3n adecuada y obtenido el consentimiento despu\u00e9s de que se present\u00f3 la demanda. El Tribunal sostuvo que la violaci\u00f3n ya hab\u00eda ocurrido cuando los datos se recopilaron sin la debida notificaci\u00f3n y consentimiento, y que el demandante ten\u00eda derecho a reclamar da\u00f1os y perjuicios por esa violaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Tercero<\/strong>, la decisi\u00f3n aclara el alcance de la disposici\u00f3n legal de da\u00f1os y perjuicios de la ley. BIPA permite da\u00f1os de $1,000 por infracci\u00f3n negligente o $5,000 por infracci\u00f3n intencional o imprudente. El Tribunal sostuvo que estos da\u00f1os no est\u00e1n sujetos a un tope o l\u00edmite, lo que podr\u00eda resultar en una responsabilidad significativa para las empresas que violan la ley.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si bien la decisi\u00f3n Cothron podr\u00eda proporcionar m\u00e1s protecci\u00f3n para la privacidad biom\u00e9trica de las personas, <strong>tambi\u00e9n puede tener un efecto escalofriante en las empresas que operan en Illinois<\/strong>. El potencial de da\u00f1os significativos, combinado con la falta de un requisito de da\u00f1o, podr\u00eda incentivar a los abogados de los demandantes a presentar m\u00e1s demandas BIPA. Esto podr\u00eda resultar en mayores costos de litigio para las empresas, lo que a su vez podr\u00eda generar precios m\u00e1s altos para los consumidores y un entorno comercial m\u00e1s desafiante para las empresas con sede en Illinois.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, la decisi\u00f3n podr\u00eda alentar a otros estados a adoptar leyes e interpretaciones similares, lo que podr\u00eda crear un mosaico de diferentes leyes de privacidad biom\u00e9trica en todo el pa\u00eds. <strong>Esto podr\u00eda crear desaf\u00edos de cumplimiento para las empresas con operaciones en varios estados y aumentar el riesgo de litigio.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En general, la decisi\u00f3n de Cothron destaca la importancia de que las empresas tomen medidas proactivas para cumplir con BIPA y otras leyes de privacidad biom\u00e9trica. Esto puede incluir la implementaci\u00f3n de pol\u00edticas s\u00f3lidas de seguridad y retenci\u00f3n de datos, la obtenci\u00f3n del consentimiento informado por escrito de las personas y el suministro de un aviso claro y visible de las pr\u00e1cticas de recopilaci\u00f3n de datos. Las empresas que no lo hagan pueden enfrentar importantes consecuencias legales y financieras, as\u00ed como da\u00f1os a la reputaci\u00f3n en una \u00e9poca en la que la privacidad y la seguridad de los datos son lo m\u00e1s importante para muchos consumidores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Resumen sobre el cumplimiento<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para garantizar el cumplimiento de la Ley de Privacidad de la Informaci\u00f3n Biom\u00e9trica de Illinois (BIPA), las empresas deben considerar tomar los siguientes pasos:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Establecer pol\u00edticas y procedimientos<\/strong>: Cree pol\u00edticas y procedimientos que describan c\u00f3mo se recopilar\u00e1, utilizar\u00e1 y almacenar\u00e1 la informaci\u00f3n biom\u00e9trica. Esto debe incluir un aviso claro y visible a las personas sobre c\u00f3mo se recopilar\u00e1, usar\u00e1 y almacenar\u00e1 su informaci\u00f3n, as\u00ed como el prop\u00f3sito de la recopilaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Obtener el consentimiento informado por escrito<\/strong>: Obtenga el consentimiento informado por escrito de las personas antes de recopilar, usar o almacenar su informaci\u00f3n biom\u00e9trica. El consentimiento debe ser espec\u00edfico y describir claramente el prop\u00f3sito de la recopilaci\u00f3n, c\u00f3mo se utilizar\u00e1 la informaci\u00f3n y c\u00f3mo se almacenar\u00e1.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Implementar salvaguardas<\/strong>: Implementar resguardos t\u00e9cnicos, administrativos y f\u00edsicos para proteger la informaci\u00f3n biom\u00e9trica. Esto puede incluir el cifrado de datos, la limitaci\u00f3n del acceso a la informaci\u00f3n biom\u00e9trica y la implementaci\u00f3n de pr\u00e1cticas seguras de almacenamiento de datos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Desarrollar pol\u00edticas de retenci\u00f3n<\/strong>: Establezca pol\u00edticas sobre cu\u00e1nto tiempo se conservar\u00e1 la informaci\u00f3n biom\u00e9trica y cu\u00e1ndo se destruir\u00e1. BIPA exige que la informaci\u00f3n biom\u00e9trica se destruya cuando se haya satisfecho el prop\u00f3sito de la recopilaci\u00f3n, o dentro de los tres a\u00f1os posteriores a la \u00faltima interacci\u00f3n del individuo con la empresa, lo que ocurra primero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Realizar auditor\u00edas peri\u00f3dicas<\/strong>: Realice auditor\u00edas peri\u00f3dicas para garantizar que la empresa cumpla con BIPA y otras leyes y reglamentos pertinentes. Esto puede incluir la revisi\u00f3n de pol\u00edticas y procedimientos, el seguimiento de las pr\u00e1cticas de recopilaci\u00f3n de datos y la garant\u00eda de que los empleados est\u00e9n capacitados sobre c\u00f3mo manejar la informaci\u00f3n biom\u00e9trica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al tomar estos pasos, las empresas pueden ayudar a garantizar que cumplen con BIPA y est\u00e1n tomando las medidas adecuadas para proteger la informaci\u00f3n biom\u00e9trica de las personas. El incumplimiento de BIPA puede tener consecuencias legales y financieras significativas, as\u00ed como da\u00f1os a la reputaci\u00f3n. Por lo tanto, es importante que las empresas tomen en serio la privacidad biom\u00e9trica y establezcan programas integrales de cumplimiento para mitigar el riesgo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Resumen sobre el descubrimiento y las fuentes de datos<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00bfCu\u00e1les son las fuentes de datos comunes que se descubren como parte de un litigio BIPA?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En un litigio de la Ley de privacidad de la informaci\u00f3n biom\u00e9trica (BIPA), se puede descubrir una variedad de fuentes de datos, seg\u00fan el alcance del caso y la informaci\u00f3n que se busca. Algunas fuentes de datos comunes que pueden estar sujetas a descubrimiento en un caso BIPA incluyen:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Informaci\u00f3n biom\u00e9trica<\/strong>: estos son los datos principales que son objeto de litigio BIPA y pueden incluir huellas dactilares, escaneos faciales y otra informaci\u00f3n biom\u00e9trica que una empresa recopila de las personas. Estos datos pueden almacenarse en dispositivos f\u00edsicos, como esc\u00e1neres, o en bases de datos electr\u00f3nicas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Registros de empleados<\/strong>: Los registros de los empleados pueden estar sujetos a descubrimiento si contienen informaci\u00f3n relacionada con la recopilaci\u00f3n de datos biom\u00e9tricos, como formularios de consentimiento, pol\u00edticas y procedimientos relacionados con la recopilaci\u00f3n y el almacenamiento de datos, y materiales de capacitaci\u00f3n para los empleados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Especificaciones t\u00e9cnicas<\/strong>: Las especificaciones t\u00e9cnicas relacionadas con la recopilaci\u00f3n y el almacenamiento de datos biom\u00e9tricos pueden ser relevantes en un caso BIPA, incluidos los detalles sobre el hardware y el software utilizados para recopilar, almacenar y proteger los datos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>sistemas informaticos<\/strong>: Los sistemas de TI pueden estar sujetos a descubrimiento en un caso BIPA, incluidos los sistemas de almacenamiento de datos, los sistemas de respaldo y los registros de acceso a datos. Esta informaci\u00f3n se puede utilizar para demostrar c\u00f3mo se recopilan, utilizan y protegen los datos, y si se produjeron infracciones o accesos no autorizados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Correo electr\u00f3nico y otras comunicaciones electr\u00f3nicas<\/strong>: Los correos electr\u00f3nicos y otras comunicaciones electr\u00f3nicas pueden ser relevantes en un caso BIPA si contienen discusiones relacionadas con la recopilaci\u00f3n, el almacenamiento o el manejo de datos biom\u00e9tricos. Esto puede incluir correos electr\u00f3nicos entre empleados, correos electr\u00f3nicos a proveedores o contratistas y comunicaciones relacionadas con el desarrollo o implementaci\u00f3n de sistemas de datos biom\u00e9tricos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Acuerdos de proveedores y contratistas<\/strong>: Los acuerdos de proveedores y contratistas pueden ser relevantes en un caso BIPA si contienen disposiciones relacionadas con la recopilaci\u00f3n y el almacenamiento de datos biom\u00e9tricos. Esta informaci\u00f3n se puede utilizar para determinar si la empresa tom\u00f3 las medidas adecuadas para proteger los datos biom\u00e9tricos y si los proveedores o contratistas fueron investigados y administrados adecuadamente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es importante tener en cuenta que las fuentes de datos sujetas a descubrimiento en un caso BIPA variar\u00e1n seg\u00fan los detalles del caso y la informaci\u00f3n que se busque. Por lo tanto, las empresas deben adoptar un enfoque integral para la recopilaci\u00f3n, el almacenamiento y el manejo de datos, y establecer pol\u00edticas y procedimientos apropiados para proteger los datos biom\u00e9tricos y minimizar el riesgo de litigio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Si desea programar una llamada con uno de nuestros expertos para analizar c\u00f3mo esta informaci\u00f3n podr\u00eda afectar a uno de sus clientes o casos, visite <\/em><\/strong><a href=\"https:\/\/idsinc.com\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong><em>idsinc.com<\/em><\/strong><\/a><\/p>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-alpha-channel-opacity has-background is-style-wide\" style=\"background-color:#e1e1e1;color:#e1e1e1\"\/>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>iDS proporciona soluciones de datos de consulta a corporaciones y bufetes de abogados de todo el mundo, lo que les otorga una ventaja decisiva, tanto dentro como fuera de la sala del tribunal. Nuestros expertos en la materia y estrategas de datos se especializan en encontrar soluciones a problemas de datos complejos, lo que garantiza que los datos se puedan aprovechar como un activo y no como un pasivo.<\/em><\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>The Illinois Supreme Court recently issued a decision in Cothron v. White Castle System, Inc., which could have significant implications for the state&#8217;s litigation landscape and business environment. The case concerned an alleged violation of Illinois&#8217; Biometric Information Privacy Act (BIPA) by White Castle, a fast-food restaurant chain, in connection with its use of fingerprint [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":4677,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,34],"tags":[],"class_list":["post-4675","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-privacy","has-post-title","has-post-date","has-post-category","has-post-tag","has-post-comment","has-post-author",""],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>New BIPA Regulations in Illinois | iDiscovery Solutions<\/title>\n<meta name=\"description\" content=\"Illinois Supreme Court decision on Cothron v. White Castle System Inc. could potentially impact the Biometric Information Privacy Act (BIPA).\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/idsinc.com\/es\/new-bipa-regulations-in-illinois\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"New BIPA Regulations in Illinois\" \/>\n<meta property=\"og:description\" content=\"Illinois Supreme Court decision on Cothron v. White Castle System Inc. could potentially impact the Biometric Information Privacy Act (BIPA).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/idsinc.com\/es\/new-bipa-regulations-in-illinois\/\" \/>\n<meta property=\"og:site_name\" content=\"iDiscovery Solutions\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/iDiscovery-Solutions-110210573904472\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-23T21:42:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-09T20:52:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/idsinc.com\/wp-content\/uploads\/2023\/02\/New-Ruling-Includes-Biometric-Data-iDiscovery-Solutions.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2500\" \/>\n\t<meta property=\"og:image:height\" content=\"1250\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"iDiscovery Solutions\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"iDiscovery Solutions\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/idsinc.com\\\/new-bipa-regulations-in-illinois\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/idsinc.com\\\/new-bipa-regulations-in-illinois\\\/\"},\"author\":{\"name\":\"iDiscovery Solutions\",\"@id\":\"https:\\\/\\\/idsinc.com\\\/en_gb\\\/#\\\/schema\\\/person\\\/bf7f03a502e8a54e558c44d0ff5d6736\"},\"headline\":\"New BIPA Regulations in Illinois\",\"datePublished\":\"2023-02-23T21:42:58+00:00\",\"dateModified\":\"2026-03-09T20:52:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/idsinc.com\\\/new-bipa-regulations-in-illinois\\\/\"},\"wordCount\":1363,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/idsinc.com\\\/en_gb\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/idsinc.com\\\/new-bipa-regulations-in-illinois\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/idsinc.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/New-Ruling-Includes-Biometric-Data-iDiscovery-Solutions.jpg\",\"articleSection\":[\"Blog\",\"Privacy + Compliance\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/idsinc.com\\\/new-bipa-regulations-in-illinois\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/idsinc.com\\\/new-bipa-regulations-in-illinois\\\/\",\"url\":\"https:\\\/\\\/idsinc.com\\\/new-bipa-regulations-in-illinois\\\/\",\"name\":\"New BIPA Regulations in Illinois | iDiscovery Solutions\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/idsinc.com\\\/en_gb\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/idsinc.com\\\/new-bipa-regulations-in-illinois\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/idsinc.com\\\/new-bipa-regulations-in-illinois\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/idsinc.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/New-Ruling-Includes-Biometric-Data-iDiscovery-Solutions.jpg\",\"datePublished\":\"2023-02-23T21:42:58+00:00\",\"dateModified\":\"2026-03-09T20:52:13+00:00\",\"description\":\"Illinois Supreme Court decision on Cothron v. White Castle System Inc. could potentially impact the Biometric Information Privacy Act (BIPA).\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/idsinc.com\\\/new-bipa-regulations-in-illinois\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/idsinc.com\\\/new-bipa-regulations-in-illinois\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/idsinc.com\\\/new-bipa-regulations-in-illinois\\\/#primaryimage\",\"url\":\"https:\\\/\\\/idsinc.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/New-Ruling-Includes-Biometric-Data-iDiscovery-Solutions.jpg\",\"contentUrl\":\"https:\\\/\\\/idsinc.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/New-Ruling-Includes-Biometric-Data-iDiscovery-Solutions.jpg\",\"width\":2500,\"height\":1250,\"caption\":\"Illinois' Supreme Court decision on Cothron v. White Castle System, Inc., could potentially impact the Biometric Information Privacy Act (BIPA).\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/idsinc.com\\\/new-bipa-regulations-in-illinois\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/idsinc.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/idsinc.com\\\/de\\\/category\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"New BIPA Regulations in Illinois\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/idsinc.com\\\/en_gb\\\/#website\",\"url\":\"https:\\\/\\\/idsinc.com\\\/en_gb\\\/\",\"name\":\"iDiscovery Solutions\",\"description\":\"Use data to your advantage in the courtroom\",\"publisher\":{\"@id\":\"https:\\\/\\\/idsinc.com\\\/en_gb\\\/#organization\"},\"alternateName\":\"iDS\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/idsinc.com\\\/en_gb\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/idsinc.com\\\/en_gb\\\/#organization\",\"name\":\"iDiscovery Solutions\",\"alternateName\":\"iDS\",\"url\":\"https:\\\/\\\/idsinc.com\\\/en_gb\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/idsinc.com\\\/en_gb\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/idsinc.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/iDS-Logo-3c-e1611176096212.png\",\"contentUrl\":\"https:\\\/\\\/idsinc.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/iDS-Logo-3c-e1611176096212.png\",\"width\":100,\"height\":73,\"caption\":\"iDiscovery Solutions\"},\"image\":{\"@id\":\"https:\\\/\\\/idsinc.com\\\/en_gb\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/iDiscovery-Solutions-110210573904472\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/idsinc\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCarv7o1MeYfCp0eZ1IrufIw\"],\"description\":\"iDS provides consultative data solutions to corporations and law firms around the world, giving them a decisive advantage \u2013 both in and out of the courtroom. iDS\u2019s subject matter experts and data strategists specialize in finding solutions to complex data problems, ensuring data can be leveraged as an asset, not a liability.\",\"email\":\"info@idsinc.com\",\"telephone\":\"+1.800.813.4832\",\"legalName\":\"iDiscovery Solutions\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/idsinc.com\\\/en_gb\\\/#\\\/schema\\\/person\\\/bf7f03a502e8a54e558c44d0ff5d6736\",\"name\":\"iDiscovery Solutions\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6009d8a07526a79850b1d0045087bcee60e562f90891f19a42de7ee7f4452529?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6009d8a07526a79850b1d0045087bcee60e562f90891f19a42de7ee7f4452529?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6009d8a07526a79850b1d0045087bcee60e562f90891f19a42de7ee7f4452529?s=96&d=mm&r=g\",\"caption\":\"iDiscovery Solutions\"},\"url\":\"https:\\\/\\\/idsinc.com\\\/es\\\/author\\\/idiscovery\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Nuevas regulaciones BIPA en Illinois | Soluciones iDiscovery","description":"La decisi\u00f3n de la Corte Suprema de Illinois sobre Cothron contra White Castle System Inc. podr\u00eda afectar potencialmente la Ley de Privacidad de la Informaci\u00f3n Biom\u00e9trica (BIPA).","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/idsinc.com\/es\/new-bipa-regulations-in-illinois\/","og_locale":"es_ES","og_type":"article","og_title":"New BIPA Regulations in Illinois","og_description":"Illinois Supreme Court decision on Cothron v. White Castle System Inc. could potentially impact the Biometric Information Privacy Act (BIPA).","og_url":"https:\/\/idsinc.com\/es\/new-bipa-regulations-in-illinois\/","og_site_name":"iDiscovery Solutions","article_publisher":"https:\/\/www.facebook.com\/iDiscovery-Solutions-110210573904472","article_published_time":"2023-02-23T21:42:58+00:00","article_modified_time":"2026-03-09T20:52:13+00:00","og_image":[{"width":2500,"height":1250,"url":"https:\/\/idsinc.com\/wp-content\/uploads\/2023\/02\/New-Ruling-Includes-Biometric-Data-iDiscovery-Solutions.jpg","type":"image\/jpeg"}],"author":"iDiscovery Solutions","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"iDiscovery Solutions","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/idsinc.com\/new-bipa-regulations-in-illinois\/#article","isPartOf":{"@id":"https:\/\/idsinc.com\/new-bipa-regulations-in-illinois\/"},"author":{"name":"iDiscovery Solutions","@id":"https:\/\/idsinc.com\/en_gb\/#\/schema\/person\/bf7f03a502e8a54e558c44d0ff5d6736"},"headline":"New BIPA Regulations in Illinois","datePublished":"2023-02-23T21:42:58+00:00","dateModified":"2026-03-09T20:52:13+00:00","mainEntityOfPage":{"@id":"https:\/\/idsinc.com\/new-bipa-regulations-in-illinois\/"},"wordCount":1363,"commentCount":0,"publisher":{"@id":"https:\/\/idsinc.com\/en_gb\/#organization"},"image":{"@id":"https:\/\/idsinc.com\/new-bipa-regulations-in-illinois\/#primaryimage"},"thumbnailUrl":"https:\/\/idsinc.com\/wp-content\/uploads\/2023\/02\/New-Ruling-Includes-Biometric-Data-iDiscovery-Solutions.jpg","articleSection":["Blog","Privacy + Compliance"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/idsinc.com\/new-bipa-regulations-in-illinois\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/idsinc.com\/new-bipa-regulations-in-illinois\/","url":"https:\/\/idsinc.com\/new-bipa-regulations-in-illinois\/","name":"Nuevas regulaciones BIPA en Illinois | Soluciones iDiscovery","isPartOf":{"@id":"https:\/\/idsinc.com\/en_gb\/#website"},"primaryImageOfPage":{"@id":"https:\/\/idsinc.com\/new-bipa-regulations-in-illinois\/#primaryimage"},"image":{"@id":"https:\/\/idsinc.com\/new-bipa-regulations-in-illinois\/#primaryimage"},"thumbnailUrl":"https:\/\/idsinc.com\/wp-content\/uploads\/2023\/02\/New-Ruling-Includes-Biometric-Data-iDiscovery-Solutions.jpg","datePublished":"2023-02-23T21:42:58+00:00","dateModified":"2026-03-09T20:52:13+00:00","description":"La decisi\u00f3n de la Corte Suprema de Illinois sobre Cothron contra White Castle System Inc. podr\u00eda afectar potencialmente la Ley de Privacidad de la Informaci\u00f3n Biom\u00e9trica (BIPA).","breadcrumb":{"@id":"https:\/\/idsinc.com\/new-bipa-regulations-in-illinois\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/idsinc.com\/new-bipa-regulations-in-illinois\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/idsinc.com\/new-bipa-regulations-in-illinois\/#primaryimage","url":"https:\/\/idsinc.com\/wp-content\/uploads\/2023\/02\/New-Ruling-Includes-Biometric-Data-iDiscovery-Solutions.jpg","contentUrl":"https:\/\/idsinc.com\/wp-content\/uploads\/2023\/02\/New-Ruling-Includes-Biometric-Data-iDiscovery-Solutions.jpg","width":2500,"height":1250,"caption":"Illinois' Supreme Court decision on Cothron v. White Castle System, Inc., could potentially impact the Biometric Information Privacy Act (BIPA)."},{"@type":"BreadcrumbList","@id":"https:\/\/idsinc.com\/new-bipa-regulations-in-illinois\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/idsinc.com\/"},{"@type":"ListItem","position":2,"name":"Blog","item":"https:\/\/idsinc.com\/de\/category\/blog\/"},{"@type":"ListItem","position":3,"name":"New BIPA Regulations in Illinois"}]},{"@type":"WebSite","@id":"https:\/\/idsinc.com\/en_gb\/#website","url":"https:\/\/idsinc.com\/en_gb\/","name":"Soluciones iDiscovery","description":"Utilice los datos a su favor en la sala del tribunal","publisher":{"@id":"https:\/\/idsinc.com\/en_gb\/#organization"},"alternateName":"iDS","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/idsinc.com\/en_gb\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/idsinc.com\/en_gb\/#organization","name":"Soluciones iDiscovery","alternateName":"iDS","url":"https:\/\/idsinc.com\/en_gb\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/idsinc.com\/en_gb\/#\/schema\/logo\/image\/","url":"https:\/\/idsinc.com\/wp-content\/uploads\/2021\/01\/iDS-Logo-3c-e1611176096212.png","contentUrl":"https:\/\/idsinc.com\/wp-content\/uploads\/2021\/01\/iDS-Logo-3c-e1611176096212.png","width":100,"height":73,"caption":"iDiscovery Solutions"},"image":{"@id":"https:\/\/idsinc.com\/en_gb\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/iDiscovery-Solutions-110210573904472","https:\/\/www.linkedin.com\/company\/idsinc","https:\/\/www.youtube.com\/channel\/UCarv7o1MeYfCp0eZ1IrufIw"],"description":"iDS ofrece soluciones de datos consultivas a corporaciones y bufetes de abogados de todo el mundo, lo que les otorga una ventaja decisiva, tanto dentro como fuera de los tribunales. Los expertos en la materia y los estrategas de datos de iDS se especializan en encontrar soluciones a problemas de datos complejos, garantizando que los datos puedan aprovecharse como un activo, no como un pasivo.","email":"info@idsinc.com","telephone":"+1.800.813.4832","legalName":"iDiscovery Solutions"},{"@type":"Person","@id":"https:\/\/idsinc.com\/en_gb\/#\/schema\/person\/bf7f03a502e8a54e558c44d0ff5d6736","name":"Soluciones iDiscovery","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6009d8a07526a79850b1d0045087bcee60e562f90891f19a42de7ee7f4452529?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6009d8a07526a79850b1d0045087bcee60e562f90891f19a42de7ee7f4452529?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6009d8a07526a79850b1d0045087bcee60e562f90891f19a42de7ee7f4452529?s=96&d=mm&r=g","caption":"iDiscovery Solutions"},"url":"https:\/\/idsinc.com\/es\/author\/idiscovery\/"}]}},"builder_content":"","_links":{"self":[{"href":"https:\/\/idsinc.com\/es\/wp-json\/wp\/v2\/posts\/4675","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/idsinc.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/idsinc.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/idsinc.com\/es\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/idsinc.com\/es\/wp-json\/wp\/v2\/comments?post=4675"}],"version-history":[{"count":1,"href":"https:\/\/idsinc.com\/es\/wp-json\/wp\/v2\/posts\/4675\/revisions"}],"predecessor-version":[{"id":9472,"href":"https:\/\/idsinc.com\/es\/wp-json\/wp\/v2\/posts\/4675\/revisions\/9472"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/idsinc.com\/es\/wp-json\/wp\/v2\/media\/4677"}],"wp:attachment":[{"href":"https:\/\/idsinc.com\/es\/wp-json\/wp\/v2\/media?parent=4675"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/idsinc.com\/es\/wp-json\/wp\/v2\/categories?post=4675"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/idsinc.com\/es\/wp-json\/wp\/v2\/tags?post=4675"}],"curies":[{"name":"gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}